{"id":2022,"date":"2026-05-28T04:00:00","date_gmt":"2026-05-28T07:00:00","guid":{"rendered":"https:\/\/revistaoeste.com\/esporte\/?p=2022"},"modified":"2026-05-28T12:03:18","modified_gmt":"2026-05-28T15:03:18","slug":"egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026","status":"publish","type":"post","link":"https:\/\/www.revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/","title":{"rendered":"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A sele\u00e7\u00e3o do Egito, \u00e9 a equipe africana mais bem-sucedida na Copa Africana de Na\u00e7\u00f5es, com sete t\u00edtulos, enfrenta desafios hist\u00f3ricos em Copas. Desde sua estreia em 1934, a participa\u00e7\u00e3o dos Fara\u00f3s no torneio foi espor\u00e1dica, com longas esperas entre as edi\u00e7\u00f5es e nenhuma vit\u00f3ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>+Leia mais noticias em\u00a0<a  href=\"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula\/\"  target=\"_blank\" rel=\"noopener noreferrer\">Oeste Esporte<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na edi\u00e7\u00e3o de 1934, na It\u00e1lia, o Egito jogou apenas uma partida, sendo eliminado na fase de grupos ap\u00f3s perder para a Hungria por 4 a 2. Em 1990, tamb\u00e9m na It\u00e1lia, a sele\u00e7\u00e3o teve uma campanha dif\u00edcil, come\u00e7ando com empates contra a Holanda (1-1) e a Rep\u00fablica da Irlanda (0-0), seguido de uma derrota para a Inglaterra (1-0).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A \u00faltima participa\u00e7\u00e3o do Egito foi em 2018, na R\u00fassia, onde n\u00e3o conquistou nenhum ponto no Grupo A. Os Fara\u00f3s perderam para o Uruguai (1-0), para a R\u00fassia (3-1) e para a Ar\u00e1bia Saudita (2-1), se juntando ao Panam\u00e1 como as \u00fanicas sele\u00e7\u00f5es a perder todas as partidas da fase de grupos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>+Leia mais <a  href=\"https:\/\/revistaoeste.com\/esporte\/felipao-fara-palestra-para-selecao-na-granja-comary-nesta-quinta-feira-28\/\"  target=\"_blank\" rel=\"noopener noreferrer\">Felip\u00e3o far\u00e1 palestra para sele\u00e7\u00e3o na Granja Comary nesta quinta-feira, 28<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a Copa do Mundo de 2026, o Egito foi sorteado no Grupo G, ao lado de B\u00e9lgica, Ir\u00e3 e Nova Zel\u00e2ndia. A sele\u00e7\u00e3o espera conquistar sua primeira vit\u00f3ria na hist\u00f3ria do Mundial, especialmente contra os <em>All Whites<\/em>, que perderam todas as suas seis partidas anteriores na competi\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sele\u00e7\u00e3o do Egito, \u00e9 a equipe africana mais bem-sucedida na Copa Africana de Na\u00e7\u00f5es, com sete t\u00edtulos, enfrenta desafios hist\u00f3ricos em&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[23,586,205,588,942],"class_list":["post-2022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grupos","category-ultimas-noticias","tag-copa-do-mundo","tag-egito","tag-futebol-africano","tag-grupo-g","tag-historia-da-copa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026<\/title>\n<meta name=\"description\" content=\"Egito busca sua primeira vit\u00f3ria na Copa do Mundo de 2026, ap\u00f3s dificuldades em edi\u00e7\u00f5es anteriores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026\" \/>\n<meta property=\"og:description\" content=\"A sele\u00e7\u00e3o do Egito, \u00e9 a equipe africana mais bem-sucedida na Copa Africana de Na\u00e7\u00f5es, com sete t\u00edtulos, enfrenta desafios hist\u00f3ricos em Copas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Oeste Esporte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oesterevista\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T15:03:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oeste Esporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026\" \/>\n<meta name=\"twitter:description\" content=\"A sele\u00e7\u00e3o do Egito, \u00e9 a equipe africana mais bem-sucedida na Copa Africana de Na\u00e7\u00f5es, com sete t\u00edtulos, enfrenta desafios hist\u00f3ricos em Copas.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png\" \/>\n<meta name=\"twitter:creator\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:site\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oeste Esporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/\"},\"author\":{\"name\":\"Oeste Esporte\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/8bac624bec4650bf2ec23768fd7ac65d\"},\"headline\":\"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026\",\"datePublished\":\"2026-05-28T07:00:00+00:00\",\"dateModified\":\"2026-05-28T15:03:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/egito.png\",\"keywords\":[\"Copa do Mundo\",\"Egito\",\"Futebol Africano\",\"Grupo G\",\"Hist\u00f3ria da Copa\"],\"articleSection\":[\"Grupos\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/\",\"name\":\"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/egito.png\",\"datePublished\":\"2026-05-28T07:00:00+00:00\",\"dateModified\":\"2026-05-28T15:03:18+00:00\",\"description\":\"Egito busca sua primeira vit\u00f3ria na Copa do Mundo de 2026, ap\u00f3s dificuldades em edi\u00e7\u00f5es anteriores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/egito.png\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/egito.png\",\"width\":640,\"height\":360,\"caption\":\"Com estrelas Salah e Marmoush, os Fara\u00f3s buscam sua primeira vit\u00f3ria em mundiais | Foto: Reprodu\u00e7\u00e3o\\\/EFA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"name\":\"Oeste Esporte\",\"description\":\"Copa sem Firula\",\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\",\"name\":\"Oeste Esporte\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"width\":500,\"height\":500,\"caption\":\"Oeste Esporte\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/oesterevista\\\/\",\"https:\\\/\\\/x.com\\\/revistaoeste\",\"https:\\\/\\\/www.youtube.com\\\/@OesteEsporte\",\"https:\\\/\\\/www.instagram.com\\\/revistaoeste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/8bac624bec4650bf2ec23768fd7ac65d\",\"name\":\"Oeste Esporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g\",\"caption\":\"Oeste Esporte\"},\"sameAs\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\"],\"url\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/author\\\/vanessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026","description":"Egito busca sua primeira vit\u00f3ria na Copa do Mundo de 2026, ap\u00f3s dificuldades em edi\u00e7\u00f5es anteriores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026","og_description":"A sele\u00e7\u00e3o do Egito, \u00e9 a equipe africana mais bem-sucedida na Copa Africana de Na\u00e7\u00f5es, com sete t\u00edtulos, enfrenta desafios hist\u00f3ricos em Copas.","og_url":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/","og_site_name":"Oeste Esporte","article_publisher":"https:\/\/www.facebook.com\/oesterevista\/","article_published_time":"2026-05-28T07:00:00+00:00","article_modified_time":"2026-05-28T15:03:18+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png","type":"image\/png"}],"author":"Oeste Esporte","twitter_card":"summary_large_image","twitter_title":"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026","twitter_description":"A sele\u00e7\u00e3o do Egito, \u00e9 a equipe africana mais bem-sucedida na Copa Africana de Na\u00e7\u00f5es, com sete t\u00edtulos, enfrenta desafios hist\u00f3ricos em Copas.","twitter_image":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png","twitter_creator":"@revistaoeste","twitter_site":"@revistaoeste","twitter_misc":{"Escrito por":"Oeste Esporte","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#article","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/"},"author":{"name":"Oeste Esporte","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/8bac624bec4650bf2ec23768fd7ac65d"},"headline":"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026","datePublished":"2026-05-28T07:00:00+00:00","dateModified":"2026-05-28T15:03:18+00:00","mainEntityOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png","keywords":["Copa do Mundo","Egito","Futebol Africano","Grupo G","Hist\u00f3ria da Copa"],"articleSection":["Grupos","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/","url":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/","name":"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#primaryimage"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png","datePublished":"2026-05-28T07:00:00+00:00","dateModified":"2026-05-28T15:03:18+00:00","description":"Egito busca sua primeira vit\u00f3ria na Copa do Mundo de 2026, ap\u00f3s dificuldades em edi\u00e7\u00f5es anteriores.","breadcrumb":{"@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#primaryimage","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/egito.png","width":640,"height":360,"caption":"Com estrelas Salah e Marmoush, os Fara\u00f3s buscam sua primeira vit\u00f3ria em mundiais | Foto: Reprodu\u00e7\u00e3o\/EFA"},{"@type":"BreadcrumbList","@id":"https:\/\/revistaoeste.com\/esporte\/egito-busca-primeira-vitoria-na-copa-do-mundo-em-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/revistaoeste.com\/esporte\/"},{"@type":"ListItem","position":2,"name":"Egito busca primeira vit\u00f3ria na Copa do Mundo em 2026"}]},{"@type":"WebSite","@id":"https:\/\/revistaoeste.com\/esporte\/#website","url":"https:\/\/revistaoeste.com\/esporte\/","name":"Oeste Esporte","description":"Copa sem Firula","publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revistaoeste.com\/esporte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/revistaoeste.com\/esporte\/#organization","name":"Oeste Esporte","url":"https:\/\/revistaoeste.com\/esporte\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","width":500,"height":500,"caption":"Oeste Esporte"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oesterevista\/","https:\/\/x.com\/revistaoeste","https:\/\/www.youtube.com\/@OesteEsporte","https:\/\/www.instagram.com\/revistaoeste\/"]},{"@type":"Person","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/8bac624bec4650bf2ec23768fd7ac65d","name":"Oeste Esporte","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g","caption":"Oeste Esporte"},"sameAs":["https:\/\/revistaoeste.com\/esporte"],"url":"https:\/\/www.revistaoeste.com\/esporte\/author\/vanessa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/2022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/comments?post=2022"}],"version-history":[{"count":1,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/2022\/revisions"}],"predecessor-version":[{"id":2052,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/2022\/revisions\/2052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media\/2051"}],"wp:attachment":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media?parent=2022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/categories?post=2022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/tags?post=2022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}