{"id":11094,"date":"2026-07-11T10:00:00","date_gmt":"2026-07-11T13:00:00","guid":{"rendered":"https:\/\/revistaoeste.com\/esporte\/?p=11094"},"modified":"2026-07-10T17:39:57","modified_gmt":"2026-07-10T20:39:57","slug":"idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao","status":"publish","type":"post","link":"https:\/\/www.revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/","title":{"rendered":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal DEPOIS DE elimina\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A sele\u00e7\u00e3o de Senegal pode iniciar um novo ciclo depois da elimina\u00e7\u00e3o na Copa do Mundo de 2026. Segundo informa\u00e7\u00f5es da imprensa francesa, Patrick Vieira, \u00eddolo da sele\u00e7\u00e3o da Fran\u00e7a e campe\u00e3o mundial em 1998, \u00e9 um dos principais nomes cotados para assumir o comando t\u00e9cnico dos Le\u00f5es de Teranga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>+ Leia mais not\u00edcias de&nbsp;<a  href=\"https:\/\/revistaoeste.com\/esporte\/\"  target=\"_blank\" rel=\"noopener noreferrer\">Oeste Esporte<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o jornal franc\u00eas L&#8217;\u00c9quipe, dirigentes da Federa\u00e7\u00e3o Senegalesa de Futebol estudam mudan\u00e7as na comiss\u00e3o t\u00e9cnica depois da queda nas oitavas de final do Mundial. O nome de Vieira aparece como favorito por reunir experi\u00eancia no futebol europeu, identifica\u00e7\u00e3o com o futebol franc\u00eas e tamb\u00e9m por suas origens familiares ligadas ao Senegal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Embora tenha defendido a sele\u00e7\u00e3o francesa durante toda a carreira como jogador, Patrick Vieira nasceu em Dacar, capital senegalesa, antes de se mudar ainda crian\u00e7a para a Fran\u00e7a. Pela sele\u00e7\u00e3o dos Bleus, conquistou a Copa do Mundo de 1998, a Eurocopa de 2000 e disputou mais de 100 partidas, tornando-se um dos maiores meio-campistas da hist\u00f3ria do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como treinador, Vieira acumula passagens por New York City, Nice, Crystal Palace, Strasbourg e, mais recentemente, pelo Genoa, da It\u00e1lia. Seu perfil agrada \u00e0 federa\u00e7\u00e3o senegalesa por aliar experi\u00eancia em grandes ligas europeias ao desenvolvimento de jovens jogadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A poss\u00edvel chegada do ex-volante acontece em um momento de instabilidade para Senegal. Al\u00e9m da elimina\u00e7\u00e3o na Copa, o ambiente da sele\u00e7\u00e3o ficou turbulento depois do meia Pape Gueye anunciar que n\u00e3o voltar\u00e1 a defender a equipe enquanto a atual comiss\u00e3o t\u00e9cnica permanecer no comando, aumentando a press\u00e3o por mudan\u00e7as.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ainda n\u00e3o h\u00e1 uma proposta oficial apresentada a Vieira, mas as conversas devem avan\u00e7ar nos pr\u00f3ximos dias. A inten\u00e7\u00e3o da Federa\u00e7\u00e3o Senegalesa \u00e9 definir rapidamente o novo treinador para iniciar o planejamento visando a Copa Africana de Na\u00e7\u00f5es e as Eliminat\u00f3rias para a Copa do Mundo de 2030. Enquanto isso, o atual t\u00e9cnico Pape Thiaw segue no cargo, mas tem perman\u00eancia considerada improv\u00e1vel depois da campanha no Mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sele\u00e7\u00e3o de Senegal pode iniciar um novo ciclo depois da elimina\u00e7\u00e3o na Copa do Mundo de 2026. Segundo informa\u00e7\u00f5es da imprensa&hellip;<\/p>\n","protected":false},"author":1,"featured_media":11110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[23,3575,29,613,192],"class_list":["post-11094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-copa-do-mundo","tag-francois","tag-futebol","tag-senegal","tag-tecnico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o na Copa do Mundo, buscando revitalizar a equipe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o na Copa do Mundo, buscando revitalizar a equipe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Oeste Esporte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oesterevista\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-11T13:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/Patrick-Vieira.png\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oeste Esporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:site\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oeste Esporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/\"},\"author\":{\"name\":\"Oeste Esporte\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/8bac624bec4650bf2ec23768fd7ac65d\"},\"headline\":\"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal DEPOIS DE elimina\u00e7\u00e3o\",\"datePublished\":\"2026-07-11T13:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Patrick-Vieira.png\",\"keywords\":[\"Copa do Mundo\",\"Fran\u00e7ois\",\"futebol\",\"Senegal\",\"t\u00e9cnico\"],\"articleSection\":[\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/\",\"name\":\"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Patrick-Vieira.png\",\"datePublished\":\"2026-07-11T13:00:00+00:00\",\"description\":\"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o na Copa do Mundo, buscando revitalizar a equipe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Patrick-Vieira.png\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Patrick-Vieira.png\",\"width\":638,\"height\":436,\"caption\":\"Patrick Vieira ex jogador j\u00e1 foi t\u00e9cnico de times como Nice e Crystal Palace | Foto: Reprodu\u00e7\u00e3o\\\/CPFC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal DEPOIS DE elimina\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"name\":\"Oeste Esporte\",\"description\":\"Copa sem Firula\",\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\",\"name\":\"Oeste Esporte\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"width\":500,\"height\":500,\"caption\":\"Oeste Esporte\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/oesterevista\\\/\",\"https:\\\/\\\/x.com\\\/revistaoeste\",\"https:\\\/\\\/www.youtube.com\\\/@OesteEsporte\",\"https:\\\/\\\/www.instagram.com\\\/revistaoeste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/8bac624bec4650bf2ec23768fd7ac65d\",\"name\":\"Oeste Esporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g\",\"caption\":\"Oeste Esporte\"},\"sameAs\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\"],\"url\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/author\\\/vanessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o","description":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o na Copa do Mundo, buscando revitalizar a equipe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o","og_description":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o na Copa do Mundo, buscando revitalizar a equipe.","og_url":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/","og_site_name":"Oeste Esporte","article_publisher":"https:\/\/www.facebook.com\/oesterevista\/","article_published_time":"2026-07-11T13:00:00+00:00","og_image":[{"width":638,"height":436,"url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/Patrick-Vieira.png","type":"image\/png"}],"author":"Oeste Esporte","twitter_card":"summary_large_image","twitter_creator":"@revistaoeste","twitter_site":"@revistaoeste","twitter_misc":{"Escrito por":"Oeste Esporte","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#article","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/"},"author":{"name":"Oeste Esporte","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/8bac624bec4650bf2ec23768fd7ac65d"},"headline":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal DEPOIS DE elimina\u00e7\u00e3o","datePublished":"2026-07-11T13:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/Patrick-Vieira.png","keywords":["Copa do Mundo","Fran\u00e7ois","futebol","Senegal","t\u00e9cnico"],"articleSection":["\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/","url":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/","name":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#primaryimage"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/Patrick-Vieira.png","datePublished":"2026-07-11T13:00:00+00:00","description":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal ap\u00f3s elimina\u00e7\u00e3o na Copa do Mundo, buscando revitalizar a equipe.","breadcrumb":{"@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#primaryimage","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/Patrick-Vieira.png","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/Patrick-Vieira.png","width":638,"height":436,"caption":"Patrick Vieira ex jogador j\u00e1 foi t\u00e9cnico de times como Nice e Crystal Palace | Foto: Reprodu\u00e7\u00e3o\/CPFC"},{"@type":"BreadcrumbList","@id":"https:\/\/revistaoeste.com\/esporte\/idolo-da-franca-pode-assumir-selecao-de-senegal-depois-de-eliminacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/revistaoeste.com\/esporte\/"},{"@type":"ListItem","position":2,"name":"\u00cddolo da Fran\u00e7a pode assumir sele\u00e7\u00e3o de Senegal DEPOIS DE elimina\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/revistaoeste.com\/esporte\/#website","url":"https:\/\/revistaoeste.com\/esporte\/","name":"Oeste Esporte","description":"Copa sem Firula","publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revistaoeste.com\/esporte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/revistaoeste.com\/esporte\/#organization","name":"Oeste Esporte","url":"https:\/\/revistaoeste.com\/esporte\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","width":500,"height":500,"caption":"Oeste Esporte"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oesterevista\/","https:\/\/x.com\/revistaoeste","https:\/\/www.youtube.com\/@OesteEsporte","https:\/\/www.instagram.com\/revistaoeste\/"]},{"@type":"Person","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/8bac624bec4650bf2ec23768fd7ac65d","name":"Oeste Esporte","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2987d05a660a8ffcae47b35d35518c167ec44856a592ec112d72c02da5110150?s=96&d=mm&r=g","caption":"Oeste Esporte"},"sameAs":["https:\/\/revistaoeste.com\/esporte"],"url":"https:\/\/www.revistaoeste.com\/esporte\/author\/vanessa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/11094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/comments?post=11094"}],"version-history":[{"count":1,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/11094\/revisions"}],"predecessor-version":[{"id":11111,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/11094\/revisions\/11111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media\/11110"}],"wp:attachment":[{"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media?parent=11094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/categories?post=11094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistaoeste.com\/esporte\/wp-json\/wp\/v2\/tags?post=11094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}